{"id":2895,"date":"2026-07-07T15:40:42","date_gmt":"2026-07-07T13:40:42","guid":{"rendered":"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/"},"modified":"2026-07-09T11:55:33","modified_gmt":"2026-07-09T09:55:33","slug":"visita-guidata-con-degustazione-e-prodotti-locali","status":"publish","type":"product","link":"https:\/\/www.vineaventis.it\/en\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/","title":{"rendered":"Visita guidata con degustazione e prodotti locali"},"content":{"rendered":"<p>Prodotto tecnico per prenotazione visita guidata con degustazione e prodotti locali.<\/p>","protected":false},"excerpt":{"rendered":"<p>Prodotto tecnico per prenotazione visita guidata con degustazione e prodotti locali.<\/p>","protected":false},"featured_media":2908,"template":"","meta":[],"product_brand":[],"product_cat":[],"product_tag":[],"class_list":["post-2895","product","type-product","status-publish","has-post-thumbnail","first","instock","virtual","taxable","purchasable","product-type-simple"],"exclude_global_add_ons":[],"addons":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Visita guidata con degustazione e prodotti locali | Vinea Ventis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vineaventis.it\/en\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visita guidata con degustazione e prodotti locali | Vinea Ventis\" \/>\n<meta property=\"og:description\" content=\"Prodotto tecnico per prenotazione visita guidata con degustazione e prodotti locali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vineaventis.it\/en\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/\" \/>\n<meta property=\"og:site_name\" content=\"Vinea Ventis\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T09:55:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/\",\"url\":\"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/\",\"name\":\"Visita guidata con degustazione e prodotti locali | Vinea Ventis\",\"isPartOf\":{\"@id\":\"https:\/\/www.vineaventis.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vineaventis.it\/wp-content\/uploads\/Vineaventis_web-54.jpg\",\"datePublished\":\"2026-07-07T13:40:42+00:00\",\"dateModified\":\"2026-07-09T09:55:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/#primaryimage\",\"url\":\"https:\/\/www.vineaventis.it\/wp-content\/uploads\/Vineaventis_web-54.jpg\",\"contentUrl\":\"https:\/\/www.vineaventis.it\/wp-content\/uploads\/Vineaventis_web-54.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vineaventis.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.vineaventis.it\/vini\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Visita guidata con degustazione e prodotti locali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vineaventis.it\/#website\",\"url\":\"https:\/\/www.vineaventis.it\/\",\"name\":\"Vinea Ventis\",\"description\":\"Azienda in franciacorta produttrice di bollicine brut, saten\",\"publisher\":{\"@id\":\"https:\/\/www.vineaventis.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vineaventis.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vineaventis.it\/#organization\",\"name\":\"Azienda in franciacorta produttrice di bollicine brut, saten\",\"url\":\"https:\/\/www.vineaventis.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.vineaventis.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vineaventis.it\/wp-content\/uploads\/vineaventis-franciacorta-logo.png\",\"contentUrl\":\"https:\/\/www.vineaventis.it\/wp-content\/uploads\/vineaventis-franciacorta-logo.png\",\"width\":624,\"height\":322,\"caption\":\"Azienda in franciacorta produttrice di bollicine brut, saten\"},\"image\":{\"@id\":\"https:\/\/www.vineaventis.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visita guidata con degustazione e prodotti locali | Vinea Ventis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vineaventis.it\/en\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/","og_locale":"en_GB","og_type":"article","og_title":"Visita guidata con degustazione e prodotti locali | Vinea Ventis","og_description":"Prodotto tecnico per prenotazione visita guidata con degustazione e prodotti locali.","og_url":"https:\/\/www.vineaventis.it\/en\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/","og_site_name":"Vinea Ventis","article_modified_time":"2026-07-09T09:55:33+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/","url":"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/","name":"Visita guidata con degustazione e prodotti locali | Vinea Ventis","isPartOf":{"@id":"https:\/\/www.vineaventis.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/#primaryimage"},"image":{"@id":"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vineaventis.it\/wp-content\/uploads\/Vineaventis_web-54.jpg","datePublished":"2026-07-07T13:40:42+00:00","dateModified":"2026-07-09T09:55:33+00:00","breadcrumb":{"@id":"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/#primaryimage","url":"https:\/\/www.vineaventis.it\/wp-content\/uploads\/Vineaventis_web-54.jpg","contentUrl":"https:\/\/www.vineaventis.it\/wp-content\/uploads\/Vineaventis_web-54.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.vineaventis.it\/vini\/visita-guidata-con-degustazione-e-prodotti-locali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vineaventis.it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.vineaventis.it\/vini\/"},{"@type":"ListItem","position":3,"name":"Visita guidata con degustazione e prodotti locali"}]},{"@type":"WebSite","@id":"https:\/\/www.vineaventis.it\/#website","url":"https:\/\/www.vineaventis.it\/","name":"Vinea Ventis","description":"Azienda in franciacorta produttrice di bollicine brut, saten","publisher":{"@id":"https:\/\/www.vineaventis.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vineaventis.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.vineaventis.it\/#organization","name":"Azienda in franciacorta produttrice di bollicine brut, saten","url":"https:\/\/www.vineaventis.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.vineaventis.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.vineaventis.it\/wp-content\/uploads\/vineaventis-franciacorta-logo.png","contentUrl":"https:\/\/www.vineaventis.it\/wp-content\/uploads\/vineaventis-franciacorta-logo.png","width":624,"height":322,"caption":"Azienda in franciacorta produttrice di bollicine brut, saten"},"image":{"@id":"https:\/\/www.vineaventis.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.vineaventis.it\/en\/wp-json\/wp\/v2\/product\/2895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vineaventis.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vineaventis.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vineaventis.it\/en\/wp-json\/wp\/v2\/media\/2908"}],"wp:attachment":[{"href":"https:\/\/www.vineaventis.it\/en\/wp-json\/wp\/v2\/media?parent=2895"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.vineaventis.it\/en\/wp-json\/wp\/v2\/product_brand?post=2895"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vineaventis.it\/en\/wp-json\/wp\/v2\/product_cat?post=2895"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vineaventis.it\/en\/wp-json\/wp\/v2\/product_tag?post=2895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}